{"id":817,"date":"2016-09-28T18:51:53","date_gmt":"2016-09-28T10:51:53","guid":{"rendered":"http:\/\/orange-transfer.com\/?p=817"},"modified":"2018-12-17T21:52:59","modified_gmt":"2018-12-17T13:52:59","slug":"half-day-hiking-trip-great-wall-mutianyu","status":"publish","type":"post","link":"https:\/\/www.orange-transfer.com\/it\/escursione-di-mezza-giornata-alla-grande-muraglia-mutianyu\/","title":{"rendered":"Sosta a Pechino, tour di 8 ore alla Grande Muraglia a Mutianyu"},"content":{"rendered":"<p>&quot;Se non riesci a raggiungere la Grande Muraglia, non sei un uomo&quot; (\u4e0d\u5230\u957f\u57ce\u975e\u597d\u6c49). Questa \u00e8 una famosa citazione del presidente cinese Mao. Essendo una delle &quot;Otto Meraviglie del Mondo Antico&quot;, la Grande Muraglia \u00e8 un&#039;attrazione imperdibile per ogni turista e viaggiatore. La Grande Muraglia \u00e8 divisa in numerose sezioni. Alcune sezioni sono molto richieste dai turisti. Diamo un&#039;occhiata a ciascuna sezione e vediamo quale fa al caso tuo.<\/p>\n<p>La Grande Muraglia a Mutianyu \u00e8 la scelta migliore per un visitatore alle prime armi di Pechino che desidera vivere un&#039;esperienza memorabile e risparmiare tempo, oltre a poter ammirare da vicino la Grande Muraglia in tutta comodit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Momenti salienti del tour<\/strong><\/p>\n<p>La sezione della Grande Muraglia a Mutianyu \u00e8 completamente restaurata e offre scenari meravigliosi.<\/p>\n<p>La sezione Mutianyu della Grande Muraglia \u00e8 unica per la sua architettura migliore. \u00c8 meno affollata e, rispetto ad altre sezioni, ha pi\u00f9 torri di guardia. Il vostro soggiorno qui sar\u00e0 piacevole e senza stress.<\/p>\n<p>A differenza del tradizionale metodo a piedi per salire in montagna tramite scale (800 in totale), la funivia (o la slitta) \u00e8 il mezzo pi\u00f9 comodo per salire e scendere dalla montagna. Questo non solo rende la visita meno faticosa, ma fa anche risparmiare tempo.<\/p>\n<p>La zona circostante 90% \u00e8 ricoperta dal verde dei pini e dei cipressi, che rendono il paesaggio incantevole e fresco tutto l&#039;anno.<\/p>\n<p>Un&#039;esperienza unica di escursione sulla Grande Muraglia accompagnati da una guida esperta e professionale<\/p>\n<p>Il chiosco di ristoro EXCURSION CHINA ai piedi della Grande Muraglia a Mutianyu fornisce gratuitamente ai nostri clienti acqua in bottiglia e attrezzatura da escursionismo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Guida, autista, veicolo e supporto al servizio clienti<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Guida:<\/strong> La vostra guida autorizzata non \u00e8 solo amichevole e parla fluentemente inglese, ma ha anche molti anni di esperienza come guida turistica, il che \u00e8 molto meglio di una normale guida turistica.<\/p>\n<p><strong>Autista:<\/strong> con oltre 5 anni di esperienza di guida, il tuo viaggio sar\u00e0 perfetto con uno dei nostri autisti locali affidabili e autorizzati<\/p>\n<p><strong>Veicolo:<\/strong> I nostri veicoli, spaziosi e completamente attrezzati, sono dotati di GPS, Wi-Fi superveloce gratuito in auto e aria condizionata (max: 7 posti).<\/p>\n<p><strong>Signor arancione Ufficio di Pechino:<\/strong> Il nostro ufficio di Pechino offre un servizio clienti 24 ore su 24, 7 giorni su 7. Siamo sempre disponibili in caso di imprevisti.<\/p>\n<p><strong>\u00a0\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Itinerario dettagliato<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>11:30 \u2013 13:30<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Prelievo dall&#039;hotel<\/strong><\/p>\n<p>Guida fino alla Grande Muraglia di Mutianyu e pranza in un bel ristorante locale Mutianyu Great Wall Store<\/p>\n<p>La vostra guida vi aspetter\u00e0 nel corridoio del vostro hotel. Sar\u00e0 facile identificarla poich\u00e9 avr\u00e0 un cartello con il vostro nome. La guida vi indirizzer\u00e0 all&#039;auto del tour, da dove l&#039;autista vi condurr\u00e0 direttamente alla sezione della Grande Muraglia a Mutianyu. Il tragitto durer\u00e0 circa un&#039;ora e mezza. Potrete gustare il resto del pranzo in un ristorante locale.<\/p>\n<p><strong>Buono a sapersi:<\/strong><\/p>\n<p>Il giorno prima della data del tour, ti consigliamo di cercare maggiori dettagli sulla guida e sull&#039;orario del ritiro tramite questo sito:\u00a0<a href=\"http:\/\/track-your-trip.html\/\" target=\"_blank\" rel=\"noopener\">traccia-il-tuo-viaggio.html<\/a>Tutte le informazioni saranno aggiornate solo 24 ore prima della data del tour. Se non riesci a ottenere le informazioni, contatta il tuo consulente di viaggio.<\/p>\n<p>&nbsp;<\/p>\n<p>Di solito, un giorno prima del tour, intorno alle 19:00, la guida di EXCURSION CHINA vi chiamer\u00e0 per confermare l&#039;orario di partenza. In caso di mancata risposta, la guida lascer\u00e0 un messaggio alla reception. Vi consigliamo di contattare la reception per ottenere tale conferma. Se non avete ricevuto alcun messaggio o chiamata dopo le 20:00, contattate l&#039;ufficio di EXCURSION CHINA a Pechino al numero<strong><em>13910694045<\/em><\/strong>Il nostro ufficio di Pechino offre un servizio clienti attivo 24 ore su 24, 7 giorni su 7. Faremo del nostro meglio per assistervi.<\/p>\n<p>Consigliamo vivamente di indossare comode scarpe da trekking il giorno del tour.<\/p>\n<p>Assicuratevi di pranzare prima di iniziare l&#039;escursione.<\/p>\n<p>Il meteo in montagna pu\u00f2 cambiare, quindi vi consigliamo vivamente di prepararvi bene a questi cambiamenti. Ricordate che questa parte della Grande Muraglia non ha negozi.<\/p>\n<p>Se hai bisogno di un servizio di trasferimento privato dall&#039;aeroporto, possiamo organizzarlo. Il costo del servizio di trasferimento privato dall&#039;aeroporto parte da 18 USD a persona.<\/p>\n<p>&nbsp;<\/p>\n<p>A differenza di altri agenti i cui veicoli non possono arrivare ai piedi della Grande Muraglia, noi possiamo guidare i nostri veicoli ai piedi della Grande Muraglia per farvi risparmiare tempo prezioso se pranziamo in un ristorante locale.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>13:30 \u2013 16:00<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Escursione sulla Grande Muraglia a Mutianyu (inclusa funivia o slittino)<\/strong><\/p>\n<p>All&#039;arrivo al chiosco di ristoro EXCURSION CHINA, situato ai piedi della Grande Muraglia, i clienti potranno ritirare dell&#039;acqua in bottiglia e un bastone da passeggio prima di prendere la navetta per l&#039;area turistica di Mutianyu.<\/p>\n<p>&nbsp;<\/p>\n<p>Puoi scegliere una delle tre opzioni disponibili per salire sulla parete: funivia, seggiovia o a piedi. Puoi decidere quale opzione preferisci al tuo arrivo. Se scegli la funivia o la seggiovia, ci vorranno sette minuti per raggiungere la cima della parete. A differenza delle prime due opzioni, la terza \u00e8 faticosa e impiega circa 45 minuti per raggiungere la cima. Ciononostante, camminare ha un effetto benefico sulla salute. Puoi passeggiare all&#039;ombra degli alberi godendoti l&#039;aria fresca di montagna.<\/p>\n<p>Dalla quattordicesima torre di guardia, cammina verso est fino alla ventitreesima, nel punto pi\u00f9 bello della sezione Mutianyu della Grande Muraglia. Poi, puoi tornare alla sesta torre di guardia e prendere uno slittino per scendere dalla montagna, un&#039;esperienza davvero divertente. (Potresti anche scegliere di fermarti alla quattordicesima torre di guardia e prendere la funivia per scendere dalla montagna senza costi aggiuntivi, oppure tornare a piedi).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Buono a sapersi:<\/strong><\/p>\n<p>Per evitare la folla e la congestione del traffico del mattino, organizziamo i nostri tour nel pomeriggio.<\/p>\n<p>Vi consigliamo di prendere una funivia (o una slitta) per salire e scendere dalla montagna. \u00c8 meno faticoso e vi fa risparmiare tempo.<\/p>\n<p><strong>Escursione sulla Grande Muraglia a Mutianyu<\/strong><\/p>\n<p><strong>16:00 \u2013 18:00<\/strong><\/p>\n<p><strong>Ritorno a Pechino<\/strong><\/p>\n<p>Dopo essere scesi ai piedi della Grande Muraglia, la guida vi indicher\u00e0 di prendere un bus navetta per il parcheggio. Da l\u00ec, l&#039;autista vi riaccompagner\u00e0 in hotel verso le 18:00.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Buono a sapersi:<\/strong><\/p>\n<p>Se prevedete di lasciare Pechino dopo il vostro tour giornaliero, vi consigliamo di effettuare il check-out dall&#039;hotel prima della partenza. Sarete trasferiti all&#039;aeroporto o alla stazione ferroviaria subito dopo il tour. Questo vi far\u00e0 risparmiare molto tempo. Il tragitto dal centro citt\u00e0 all&#039;aeroporto dura circa un&#039;ora. Per i voli nazionali, dovrete essere in aeroporto un&#039;ora e mezza prima dell&#039;imbarco. Per i voli internazionali, il tempo necessario \u00e8 molto pi\u00f9 lungo, solitamente 2 ore e mezza. Durante la prenotazione del tour, vi consigliamo di informarci se prevedete di partire subito dopo il tour. Questo ci permetter\u00e0 di prendere le disposizioni necessarie.<\/p>\n<p>Offriamo il trasferimento privato da\/per aeroporto\/stazione ferroviaria (prezzo a partire da 18 USD a persona).<\/p>\n<p><strong>Prezzo del tour<\/strong><\/p>\n<p>Adulti (et\u00e0&gt;12) Bambini (et\u00e0 2-12) Neonati (et\u00e0&lt;2)<\/p>\n<p>99 USD 88 USD gratis<\/p>\n<p>Questo tour \u00e8 disponibile tutti i giorni, con partenza garantita. Farai parte di un piccolo gruppo di massimo 6 persone.<\/p>\n<p>&nbsp;<\/p>\n<p>Il prezzo include:<\/p>\n<p>Biglietti d&#039;ingresso alla Grande Muraglia a Mutianyu<\/p>\n<p>Trasporto tra il tuo hotel di Pechino e la Grande Muraglia<\/p>\n<p>Pranzo al ristorante Xinshuangquan<\/p>\n<p>Servizio di guida turistica in montagna di lingua inglese<\/p>\n<p>Snack e acqua potabile sulla Grande Muraglia<\/p>\n<p>Servizio di trasferimento in bus navetta dalla Porta della Grande Muraglia a Mutianyu ai piedi della Grande Muraglia<\/p>\n<p>Funivia (o slittino) andata e ritorno su e gi\u00f9 per la montagna<\/p>\n<p>Il prezzo non include:<\/p>\n<p>Spese personali.<\/p>\n<p>Mance per la guida e l&#039;autista (di solito 50-100 CNY a persona per la guida, 25-50 CNY a persona per l&#039;autista). Non sono obbligatorie, ma rappresentano un ottimo incentivo per loro.<\/p>\n<p>Trasferimento aeroportuale. Clicca qui per prenotare il servizio di trasferimento aeroportuale. (Prezzo a partire da 18 USD a persona)<\/p>\n<p>Questo \u00e8 un tour giornaliero con partenza garantita. I nostri tour sono solitamente personalizzati in base alle esigenze dei nostri clienti. Preferiamo lavorare con gruppi pi\u00f9 piccoli, di massimo 6 persone.<\/p>\n<p><strong>Il prezzo include:<\/strong><\/p>\n<ul>\n<li>Biglietti d&#039;ingresso alla Grande Muraglia a Mutianyu<\/li>\n<li>Trasporto tra il tuo hotel di Pechino e la Grande Muraglia<\/li>\n<li>Servizio di guida turistica in montagna di lingua inglese<\/li>\n<li>Snack e acqua potabile sulla Grande Muraglia<\/li>\n<li>Servizio di trasferimento in bus navetta dalla Porta della Grande Muraglia a Mutianyu ai piedi della Grande Muraglia<\/li>\n<li>Funivia (o slittino) andata e ritorno su e gi\u00f9 per la montagna<\/li>\n<\/ul>\n<p><strong>Il prezzo non include:<\/strong><\/p>\n<ul>\n<li>Spese personali.<\/li>\n<li>Pranzo.<\/li>\n<\/ul>\n<p>Mance per la guida e l&#039;autista (di solito 50-100 CNY a persona per la guida, 25-50 CNY a persona per l&#039;autista). Non sono obbligatorie, ma sarebbero molto apprezzate.<\/p>\n<p><strong>Politica di cancellazione del signor Orange per i tour di Pechino<\/strong><\/p>\n<p>Se non fossimo in grado di rispettare il contratto a causa di circostanze impreviste come guerra, alluvione, tifone, incendio, scioperi, tempeste, terremoti o qualsiasi altra situazione imprevista, faremo del nostro meglio per informare i clienti sulla prossima opportunit\u00e0 possibile e offrire le migliori soluzioni possibili. In questo caso, la fattura verr\u00e0 saldata come segue:<\/p>\n<ul>\n<li>Fino a 7 giorni prima della partenza: 100% verr\u00e0 rimborsato, escluse le penali applicate da hotel, ferrovie, compagnie aeree e PayPal, se applicabili. Tutte le penali saranno specificate.<\/li>\n<li>Da 3 a 7 giorni prima della partenza: 90% verr\u00e0 rimborsato. Sono escluse le penali relative a hotel, ferrovie, compagnie aeree e PayPal, se applicabili. Tutte le penali saranno dettagliate.<\/li>\n<li>Entro 3 giorni prima della partenza: nessun rimborso.<\/li>\n<\/ul>\n<p>Una volta iniziato il tour, non saremo in grado di effettuare alcun rimborso per i servizi annullati a causa di mancata partecipazione, partenza anticipata, arrivo posticipato o giorni di tour persi.<\/p>\n<ul>\n<li>Per gruppi di oltre 10 persone: questo \u00e8 un caso speciale e pu\u00f2 variare da caso a caso. Ti consigliamo vivamente di contattare il tuo consulente di viaggio per conoscere le condizioni di cancellazione del tuo gruppo.<\/li>\n<\/ul>\n<p><strong>Area di prelievo e rientro in hotel<\/strong><\/p>\n<p>L&#039;area di prelievo e rientro in hotel deve trovarsi all&#039;interno del quarto anello stradale di Pechino. Il tuo consulente di viaggio ti informer\u00e0 di eventuali costi aggiuntivi dovuti alla distanza percorsa oltre il quarto anello stradale di Pechino.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Cosa ci rende diversi<\/strong><\/p>\n<ul>\n<li>La nostra guida e il nostro autista non sono solo cordiali, affidabili e degni di fiducia, ma anche professionisti esperti e autorizzati.<\/li>\n<li>Con oltre 8 anni di esperienza nella visita alla Grande Muraglia, forniamo servizi di prima classe pertinenti, affidabili e ottimizzati.<\/li>\n<li>Adattiamo i nostri tour alle esigenze dei nostri clienti. Ecco perch\u00e9 diverse migliaia di clienti soddisfatti ogni anno garantiscono la nostra capacit\u00e0 di fare le cose a modo loro.<\/li>\n<li>Offriamo GRATUITAMENTE ai nostri clienti bastoncini da trekking, acqua, marsupio, GPS, kit di pronto soccorso e walkie-talkie.<\/li>\n<li>Vantiamo una solida reputazione per la nostra flessibilit\u00e0 imbattibile, senza deviazioni per lo shopping! Nessun costo nascosto! E un ottimo rapporto qualit\u00e0-prezzo!<\/li>\n<li>Siamo la prima agenzia di viaggi in Cina a offrire la formula NO SHOPPING su tutti i nostri itinerari turistici.<\/li>\n<li>Forse non offriamo i prezzi pi\u00f9 bassi per i tour, ma i nostri eccellenti servizi vanno oltre ogni misura per garantire ai nostri clienti un tour soddisfacente, divertente e memorabile.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>\u201cIf you fail to reach the Great Wall, you\u2019re not a man.\u201d(\u4e0d\u5230\u957f\u57ce\u975e\u597d\u6c49) This is a famous quotation made by China\u2019s Chairman Mao. The Great Wall being one of the \u201cEight Wonders of the Ancient World\u201d is a must-see attraction to every tourist and travelers. The Great Wall is divided into many sections. Some sections are [&hellip;]<\/p>","protected":false},"author":1,"featured_media":238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20,5],"tags":[21,22],"_links":{"self":[{"href":"https:\/\/www.orange-transfer.com\/it\/wp-json\/wp\/v2\/posts\/817"}],"collection":[{"href":"https:\/\/www.orange-transfer.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.orange-transfer.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.orange-transfer.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orange-transfer.com\/it\/wp-json\/wp\/v2\/comments?post=817"}],"version-history":[{"count":1,"href":"https:\/\/www.orange-transfer.com\/it\/wp-json\/wp\/v2\/posts\/817\/revisions"}],"predecessor-version":[{"id":2596,"href":"https:\/\/www.orange-transfer.com\/it\/wp-json\/wp\/v2\/posts\/817\/revisions\/2596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orange-transfer.com\/it\/wp-json\/wp\/v2\/media\/238"}],"wp:attachment":[{"href":"https:\/\/www.orange-transfer.com\/it\/wp-json\/wp\/v2\/media?parent=817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orange-transfer.com\/it\/wp-json\/wp\/v2\/categories?post=817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.orange-transfer.com\/it\/wp-json\/wp\/v2\/tags?post=817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}